{"id":311,"date":"2026-04-16T18:53:11","date_gmt":"2026-04-16T21:53:11","guid":{"rendered":"https:\/\/www3.unicentro.br\/observatorioeconomico\/?p=311"},"modified":"2026-04-16T18:53:11","modified_gmt":"2026-04-16T21:53:11","slug":"pobreza-e-desigualdade","status":"publish","type":"post","link":"https:\/\/www3.unicentro.br\/observatorioeconomico\/pobreza-e-desigualdade\/","title":{"rendered":"Pobreza e desigualdade"},"content":{"rendered":"<p>O n\u00famero de fam\u00edlias em situa\u00e7\u00e3o de pobreza aumentou no inicio de 2026 em Guarapuava.<\/p>\n<p>Segundo dados do Cadastro \u00danico, o contingente de fam\u00edlias com renda mensal de at\u00e9 R$ 218,00 subiu de 10.987 em janeiro para 11.135 em fevereiro \u2014 uma alta de\u00a0<b>1,35%<\/b>. O avan\u00e7o local superou as m\u00e9dias registradas no Paran\u00e1 (0,89%) e no Brasil (0,49%) no mesmo per\u00edodo.<\/p>\n<p>Confira todos os detalhes:\u00a0<a href=\"https:\/\/www3.unicentro.br\/observatorioeconomico\/socioeconomicos\/pobreza-e-desigualdade\/\">Pobreza e Desigualdade<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00famero de fam\u00edlias em situa\u00e7\u00e3o de pobreza aumentou no inicio de 2026 em Guarapuava<\/p>\n","protected":false},"author":942,"featured_media":313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[24,10],"tags":[],"class_list":["post-311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaques","category-publicacoes"],"_links":{"self":[{"href":"https:\/\/www3.unicentro.br\/observatorioeconomico\/wp-json\/wp\/v2\/posts\/311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www3.unicentro.br\/observatorioeconomico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www3.unicentro.br\/observatorioeconomico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www3.unicentro.br\/observatorioeconomico\/wp-json\/wp\/v2\/users\/942"}],"replies":[{"embeddable":true,"href":"https:\/\/www3.unicentro.br\/observatorioeconomico\/wp-json\/wp\/v2\/comments?post=311"}],"version-history":[{"count":2,"href":"https:\/\/www3.unicentro.br\/observatorioeconomico\/wp-json\/wp\/v2\/posts\/311\/revisions"}],"predecessor-version":[{"id":314,"href":"https:\/\/www3.unicentro.br\/observatorioeconomico\/wp-json\/wp\/v2\/posts\/311\/revisions\/314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www3.unicentro.br\/observatorioeconomico\/wp-json\/wp\/v2\/media\/313"}],"wp:attachment":[{"href":"https:\/\/www3.unicentro.br\/observatorioeconomico\/wp-json\/wp\/v2\/media?parent=311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www3.unicentro.br\/observatorioeconomico\/wp-json\/wp\/v2\/categories?post=311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www3.unicentro.br\/observatorioeconomico\/wp-json\/wp\/v2\/tags?post=311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}