{"id":41335,"date":"2025-04-15T10:13:13","date_gmt":"2025-04-15T13:13:13","guid":{"rendered":"https:\/\/www3.unicentro.br\/noticias\/?p=41335"},"modified":"2025-04-15T10:13:13","modified_gmt":"2025-04-15T13:13:13","slug":"violencia-contra-as-mulheres-em-guarapuava-e-tema-de-livro-publicado-pela-unicentro","status":"publish","type":"post","link":"https:\/\/www3.unicentro.br\/noticias\/2025\/04\/15\/violencia-contra-as-mulheres-em-guarapuava-e-tema-de-livro-publicado-pela-unicentro\/","title":{"rendered":"Viol\u00eancia contra as mulheres em Guarapuava \u00e9 tema de livro publicado pela Unicentro"},"content":{"rendered":"<p style=\"text-align: justify\">O combate \u00e0 viol\u00eancia contra as mulheres feito pelo N\u00facleo Maria da Penha (Numape) em Guarapuava inspirou a publica\u00e7\u00e3o de um livro. Profissionais que fizeram parte da equipe do projeto da Universidade Estadual do Centro-Oeste (Unicentro) durante os seus primeiros anos de atua\u00e7\u00e3o uniram a extens\u00e3o e a pesquisa para escrever sobre os diversos tipos de viol\u00eancia que as guarapuavanas que procuram o servi\u00e7o relatam sofrer.<\/p>\n<p style=\"text-align: justify\">Intitulado \u201cViol\u00eancias contra as mulheres em Guarapuava: an\u00e1lises cr\u00edticas a partir da a\u00e7\u00e3o\/reflex\u00e3o do N\u00facleo Maria da Penha (Numape)\u201d, o livro foi organizado pelas professoras Angela Maria Moura Costa, do Departamento de Servi\u00e7o Social da Unicentro, e Ana Claudia da Silva Abreu, do curso de Direito do Centro Universit\u00e1rio Campo Real. O processo de editora\u00e7\u00e3o da obra foi feito pela Editora Unicentro.<\/p>\n<p style=\"text-align: justify\">\u201cA ideia de publicar o livro se deu a partir da nossa experi\u00eancia extensionista e do nosso grupo de estudos, que nos deu subs\u00eddio para atender as mulheres em situa\u00e7\u00e3o de viol\u00eancia dom\u00e9stica e familiar e desenvolver as a\u00e7\u00f5es de preven\u00e7\u00e3o \u00e0 viol\u00eancia na cidade e regi\u00e3o. Com o livro, quer\u00edamos deixar registradas a nossa pr\u00e1tica e parte dos desafios e potencialidades dessa viv\u00eancia\u201d, contextualiza a organizadora Angela, que foi coordenadora do Numape entre 2018 e 2021.<\/p>\n<div class=\"wp-block-image\" style=\"text-align: justify\">\n<div id=\"attachment_41336\" style=\"width: 267px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-41336\" class=\"wpa-warning wpa-image-missing-alt wp-image-41336\" src=\"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2025\/04\/Captura-de-tela-2025-04-08-143442.png\" alt=\"\" width=\"257\" height=\"369\" data-warning=\"Missing alt text\" srcset=\"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2025\/04\/Captura-de-tela-2025-04-08-143442.png 628w, https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2025\/04\/Captura-de-tela-2025-04-08-143442-400x574.png 400w, https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2025\/04\/Captura-de-tela-2025-04-08-143442-255x366.png 255w\" sizes=\"auto, (max-width: 257px) 100vw, 257px\" \/><p id=\"caption-attachment-41336\" class=\"wp-caption-text\">Livro foi organizado pelas professoras Angela Maria Moura Costa e Ana Claudia Silva Abreu.<\/p><\/div>\n<\/div>\n<p style=\"text-align: justify\">Dividida em cinco cap\u00edtulos, a produ\u00e7\u00e3o traz dados e an\u00e1lises cient\u00edficas sobre a realidade de mulheres v\u00edtimas de viol\u00eancia em Guarapuava. Os textos s\u00e3o fruto das discuss\u00f5es feitas no \u00e2mbito do Grupo de Estudos e Pesquisas Feminismos e Viol\u00eancias de G\u00eanero, criado em 2018 para a capacita\u00e7\u00e3o das extensionistas do Numape, que s\u00e3o profissionais e estagi\u00e1rias das \u00e1reas de Servi\u00e7o Social, Direito e Psicologia.<\/p>\n<p style=\"text-align: justify\">\u201cPara cada etapa de constru\u00e7\u00e3o do N\u00facleo, cada estrat\u00e9gia definida, cada a\u00e7\u00e3o desenvolvida, sempre partimos do nosso grupo de estudos e para ele volt\u00e1vamos, como forma de repensar as pr\u00e1ticas e recriar novas estrat\u00e9gias. O livro \u00e9 produto da nossa articula\u00e7\u00e3o te\u00f3rico-pr\u00e1tica-pol\u00edtica dentro da viv\u00eancia do Numape\u201d, relaciona Angela. Essa perspectiva \u00e9 partilhada pela tamb\u00e9m organizadora do livro Ana Claudia, que foi orientadora pedag\u00f3gica do Numape entre 2019 e 2021. \u201cEsse grupo foi fundamental para o entendimento das quest\u00f5es de g\u00eanero e os demais marcadores que atravessam a viv\u00eancia das mulheres com a viol\u00eancia\u201d, avalia.<\/p>\n<p style=\"text-align: justify\">O Numape \u00e9 um projeto de extens\u00e3o interdisciplinar que realiza atendimentos a mulheres que foram v\u00edtimas de viol\u00eancia dom\u00e9stica, assessorando-as em quest\u00f5es jur\u00eddicas, psicol\u00f3gicas e sociais. \u201cS\u00e3o olhares diversos sobre a viol\u00eancia que se somam para possibilitar um atendimento com uma perspectiva de g\u00eanero, preocupado em ouvir as mulheres em situa\u00e7\u00e3o de viol\u00eancia e atender \u00e0s suas diversas demandas, fortalecendo-as para que seja poss\u00edvel romper com o ciclo de viol\u00eancia\u201d, contextualiza Ana Claudia.<\/p>\n<p style=\"text-align: justify\">Para as organizadoras, o livro \u00e9 um compilado de informa\u00e7\u00f5es que ajudam na divulga\u00e7\u00e3o do projeto e de dados sobre a viol\u00eancia contra as mulheres guarapuavanas. \u201cO livro pode subsidiar profissionais que atuam com situa\u00e7\u00f5es de viol\u00eancia na cidade e regi\u00e3o e, de alguma forma, pode contribuir com as mulheres que est\u00e3o em situa\u00e7\u00e3o de viol\u00eancia, por desnaturalizar o fen\u00f4meno e indicar caminhos de acesso \u00e0s pol\u00edticas p\u00fablicas\u201d, vislumbra Angela. \u201cOs resultados s\u00e3o satisfat\u00f3rios pois realiza uma das finalidades da extens\u00e3o universit\u00e1ria que \u00e9 apresentar os resultados do projeto para a comunidade universit\u00e1ria e externa\u201d, complementa Ana.<\/p>\n<p style=\"text-align: justify\"><strong>Visibilidade \u00e0s pesquisas sobre o tema<\/strong><\/p>\n<p style=\"text-align: justify\">Uma das autoras que contribu\u00edram no livro \u00e9 a Ana Claudia Marochi, que atualmente \u00e9 professora do curso de Pedagogia na Universidade Estadual do Norte do Paran\u00e1 (Uenp). Embora n\u00e3o tenha feito parte da equipe do Numape, ela participou efetivamente do grupo de estudos vinculado ao projeto de extens\u00e3o. Na obra, a docente publicou um cap\u00edtulo sobre quem s\u00e3o e quais as viol\u00eancias sofridas pelas mulheres guarapuavanas, utilizando como metodologia a an\u00e1lise de prontu\u00e1rios e entrevistas com nove mulheres atendidas pelo N\u00facleo. O Numape disponibilizou dados para que a pesquisadora fizesse a articula\u00e7\u00e3o te\u00f3rica em torno deles.<\/p>\n<p style=\"text-align: justify\">\u201cQuando elas chegam l\u00e1, elas relatam situa\u00e7\u00f5es do cotidiano que permitem a gente fazer uma an\u00e1lise cient\u00edfica de quais s\u00e3o as caracter\u00edsticas mais comuns que as mulheres que sofrem viol\u00eancia passam\u201d, avalia a autora. Segundo a pesquisadora, a viol\u00eancia mais relatada pelas mulheres atendidas pelo Numape \u00e9 a psicol\u00f3gica, seguida das viol\u00eancias moral, patrimonial e f\u00edsica, que costuma surgir quando todas as outras j\u00e1 atingiram a v\u00edtima.<\/p>\n<div class=\"wp-block-image\">\n<div id=\"attachment_41391\" style=\"width: 396px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-41391\" class=\"wpa-warning wpa-image-missing-alt wp-image-41391\" src=\"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2025\/04\/IMG-20180308-WA0025.jpg\" alt=\"\" width=\"386\" height=\"290\" data-warning=\"Missing alt text\" srcset=\"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2025\/04\/IMG-20180308-WA0025.jpg 1152w, https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2025\/04\/IMG-20180308-WA0025-768x576.jpg 768w, https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2025\/04\/IMG-20180308-WA0025-400x300.jpg 400w, https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2025\/04\/IMG-20180308-WA0025-800x600.jpg 800w, https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2025\/04\/IMG-20180308-WA0025-255x191.jpg 255w\" sizes=\"auto, (max-width: 386px) 100vw, 386px\" \/><p id=\"caption-attachment-41391\" class=\"wp-caption-text\">Livro re\u00fane textos de profissionais de diversas \u00e1reas que atuaram no combate \u00e0 viol\u00eancia dom\u00e9stica no Numape (Foto: arquivo pessoal)<\/p><\/div>\n<\/div>\n<p style=\"text-align: justify\">Para Ana, a publica\u00e7\u00e3o contribui para a difus\u00e3o do conhecimento sobre o assunto. \u201c\u00c9 importante para a divulga\u00e7\u00e3o de todas essas an\u00e1lises que a gente faz e tamb\u00e9m para que outras mulheres leiam. Quando as mulheres que tem acesso a esses textos conseguem ler, elas tamb\u00e9m conseguem perceber se est\u00e3o em rela\u00e7\u00f5es abusivas e violentas\u201d, projeta a professora da Uenp.<\/p>\n<p style=\"text-align: justify\">Al\u00e9m da professora Ana e das organizadoras da obra, assinam cap\u00edtulos do livro: psic\u00f3logas, assistentes sociais, advogadas e mais uma professora de Servi\u00e7o Social.<\/p>\n<p style=\"text-align: justify\"><strong>O conte\u00fado<\/strong><\/p>\n<p style=\"text-align: justify\">O livro \u201cViol\u00eancias contra as mulheres em Guarapuava: an\u00e1lises cr\u00edticas a partir da a\u00e7\u00e3o\/reflex\u00e3o do N\u00facleo Maria da Penha (Numape)\u201d traz textos em diversas ramifica\u00e7\u00f5es do tema. Confira os t\u00edtulos e autoras que comp\u00f5em a obra:<\/p>\n<ul>\n<li style=\"text-align: justify\"><strong>Cap\u00edtulo 1:<\/strong> Hist\u00f3ria e constru\u00e7\u00e3o do N\u00facleo Maria da Penha (Numape): uma experi\u00eancia de extens\u00e3o no munic\u00edpio de Guarapuava \u2013 PR, por Angela Maria Moura Costa, Ana Claudia da Silva Abreu e Priscila Ferreira Fortini<\/li>\n<li style=\"text-align: justify\"><strong>Cap\u00edtulo 2:<\/strong> A viol\u00eancia como categoria estruturante do patriarcado e a condi\u00e7\u00e3o das mulheres que procuram o Numape\/Guarapuava-PR, por Ana Claudia Marochi<\/li>\n<li style=\"text-align: justify\"><strong>Cap\u00edtulo 3:<\/strong> O ciclo da viol\u00eancia dom\u00e9stica e familiar contra mulheres: dilemas e supera\u00e7\u00e3o, por Angela Maria Moura Costa, Micheli Souza Cordeiro e Bruna Almerinda Santos de Carvalho<\/li>\n<li style=\"text-align: justify\"><strong>Cap\u00edtulo 4:<\/strong> Perfil dos feminic\u00eddios ocorridos na comarca de Guarapuava nos anos de 2015 a 2020, por Ana Claudia da Silva Abreu e Kamila Dib Kaminski<\/li>\n<li style=\"text-align: justify\"><strong>Cap\u00edtulo 5:<\/strong> Faces e determinantes da viol\u00eancia contra as mulheres: contribui\u00e7\u00f5es da interdisciplinaridade a partir das reflex\u00f5es do N\u00facleo Maria da Penha \u2013 Guarapuava, por Ros\u00e2ngela Bujokas de Siqueira, Jully Annye Gallo Lacerda e Luana Maximo Gasperotto<\/li>\n<\/ul>\n<p style=\"text-align: justify\">O livro pode ser acessado na \u00edntegra em sua vers\u00e3o digital atrav\u00e9s do <span style=\"color: #808000\"><span style=\"color: #800080\"><a style=\"color: #800080\" href=\"https:\/\/www3.unicentro.br\/edunicentro\/e-books\/\" target=\"_blank\" rel=\"noopener\"><strong>site da Editora Unicentro<\/strong><\/a><\/span><span style=\"color: #000000\">.<\/span><\/span><\/p>\n<p><em>Por Amanda Pieta<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Textos articulam estudos e experi\u00eancias do N\u00facleo Maria da Penha (Numape) <a class=\"continue\" href=\"https:\/\/www3.unicentro.br\/noticias\/2025\/04\/15\/violencia-contra-as-mulheres-em-guarapuava-e-tema-de-livro-publicado-pela-unicentro\/\"><span> Viol\u00eancia contra as mulheres em Guarapuava \u00e9 tema de livro publicado pela Unicentro<\/span><\/a><\/p>\n","protected":false},"author":274,"featured_media":41341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"fifu_image_url":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2025\/04\/maos-de-mulheres-close-up-com-o-simbolo-do-feminismo_23-2148409927.jpg","fifu_image_alt":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[2],"tags":[],"class_list":["post-41335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"mobiconnector_feature_image":{"id":41341,"alt_text":"","caption":"","description":"","media_type":"image","post":41335,"source_url":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2025\/04\/maos-de-mulheres-close-up-com-o-simbolo-do-feminismo_23-2148409927.jpg","mobiconnector_small":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_medium":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_x_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/"},"mobiconnector_total_comments":{"approved":0,"spam":0,"trash":0,"post-trashed":0,"all":0,"total_comments":0,"moderated":0},"mobiconnector_author_name":"Amanda Padilha Pieta","mobiconnector_total_views":"1","mobiconnector_comments":[],"mobiconnector_posts_incategory":[{"ID":51863,"post_author":"9","post_date":"2026-05-13T11:44:18","post_date_gmt":"2026-05-13T14:44:18","post_content":"&nbsp;\r\n<h3 style=\"text-align: center\" data-start=\"1775\" data-end=\"1789\"><sup><em>Evento anual da Abeu re\u00fane representantes de mais de 130 editoras para debater inova\u00e7\u00e3o, leitura e os desafios da edi\u00e7\u00e3o acad\u00eamica no Brasil<\/em><\/sup><\/h3>\r\n\r\n<hr \/>\r\n<p style=\"text-align: justify\">A Editora Unicentro, da <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Universidade Estadual do Centro-Oeste<\/span><\/span>, participa da 38\u00aa Reuni\u00e3o Anual da <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Associa\u00e7\u00e3o Brasileira das Editoras Universit\u00e1rias<\/span><\/span> (ABEU), realizada ao longo desta semana, na <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Universidade Federal da Bahia<\/span><\/span> (UFBA). Representam a institui\u00e7\u00e3o no encontro a coordenadora da editora, <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Beatriz Anselmo Olinto<\/span><\/span>, e a assessora editorial <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Renata Daletese<\/span><\/span>. O evento re\u00fane representantes de editoras universit\u00e1rias de todo o pa\u00eds para quatro dias de debates, palestras e troca de experi\u00eancias sobre os rumos da produ\u00e7\u00e3o editorial acad\u00eamica brasileira.<\/p>\r\n<p style=\"text-align: justify\">Com o tema \u201cNovos modos de ler: o futuro da edi\u00e7\u00e3o universit\u00e1ria\u201d, a programa\u00e7\u00e3o aborda quest\u00f5es ligadas \u00e0 inova\u00e7\u00e3o no setor, incluindo o uso da intelig\u00eancia artificial no ambiente acad\u00eamico, gest\u00e3o de metadados, circula\u00e7\u00e3o do conhecimento cient\u00edfico e novas pr\u00e1ticas de leitura. O evento tamb\u00e9m conta com apresenta\u00e7\u00f5es de pesquisas cient\u00edficas e relatos de experi\u00eancias desenvolvidas pelas editoras associadas \u00e0 entidade.<\/p>\r\n<p style=\"text-align: justify\">Al\u00e9m das atividades acad\u00eamicas, a reuni\u00e3o promove a Assembleia Geral da Abeu, momento em que ser\u00e3o discutidas pautas de interesse das institui\u00e7\u00f5es filiadas e apresentado o relat\u00f3rio da atual gest\u00e3o da associa\u00e7\u00e3o. O encerramento do evento ser\u00e1 conduzido por Felipe Gomberg, presidente da entidade e diretor da Editora PUC-Rio.<\/p>\r\n<p style=\"text-align: justify\">Segundo Gomberg, a reuni\u00e3o anual representa um importante espa\u00e7o de integra\u00e7\u00e3o entre as editoras universit\u00e1rias brasileiras. \u201cAs reuni\u00f5es anuais s\u00e3o um momento especial para a Abeu. \u00c9 um espa\u00e7o de encontro dessa nossa incr\u00edvel rede de mais de 130 editoras universit\u00e1rias brasileiras. Trata-se de uma semana de intensa troca entre os profissionais do livro de nossas editoras, de relatos de experi\u00eancias e \u2018cases\u2019, de confer\u00eancias e workshops, com alguns dos melhores do nosso mercado. \u00c9 ainda especial que a edi\u00e7\u00e3o deste ano ocorra na UFBA, na Bahia, estado com forte presen\u00e7a de tradicionais editoras universit\u00e1rias\u201d, destaca.<\/p>\r\n<p style=\"text-align: justify\"><b><\/b><span style=\"font-weight: 400\">Anfitri\u00e3 do encontro, a Editora da Universidade Federal da Bahia (Edufba) consolidou-se como um pilar na difus\u00e3o de conhecimento do pa\u00eds, unindo tradi\u00e7\u00e3o e inova\u00e7\u00e3o em seu cat\u00e1logo, que conta com mais de tr\u00eas mil t\u00edtulos. \u201c<\/span><span style=\"font-weight: 400\">\u00c9 um momento de muita expectativa para a Edufba e as editoras universit\u00e1rias baianas parceiras receberem o principal evento de edi\u00e7\u00e3o acad\u00eamica do Brasil. Vivemos um momento de mudan\u00e7as profundas nas pr\u00e1ticas de leitura e nas formas de produ\u00e7\u00e3o e circula\u00e7\u00e3o do conhecimento e precisamos discutir sobre como lidar com esse cen\u00e1rio. Nesse sentido, estamos propondo tamb\u00e9m a amplia\u00e7\u00e3o desse debate com a participa\u00e7\u00e3o de editores de pa\u00edses da Am\u00e9rica Latina<\/span><span style=\"font-weight: 400\">\u201d afirma Susane Barros, diretora da Edufba.<\/span><\/p>\r\n<p style=\"text-align: justify\">A 38\u00aa Reuni\u00e3o Anual da Abeu \u00e9 organizada pela Associa\u00e7\u00e3o Brasileira das Editoras Universit\u00e1rias, pela Universidade Federal da Bahia e pela Edufba, com apoio de institui\u00e7\u00f5es baianas de ensino superior, entre elas a Universidade Estadual de Feira de Santana, a Universidade Federal do Rec\u00f4ncavo da Bahia, a Universidade Estadual de Santa Cruz, a Universidade do Estado da Bahia e a Universidade Estadual do Sudoeste da Bahia.<\/p>\r\n&nbsp;\r\n\r\n<em>Com informa\u00e7\u00f5es da Editora Unicentro<\/em>\r\n\r\n<hr \/>\r\n\r\n<span style=\"color: #808000\"><strong>Voc\u00ea j\u00e1 conhece o canal de transmiss\u00e3o da Unicentro no WhatsApp?<\/strong><\/span>\r\n\r\nL\u00e1, voc\u00ea encontra not\u00edcias fresquinhas e em primeira m\u00e3o, al\u00e9m de comunicados oficiais, eventos, conquistas da galera e muito mais!\u00a0<span style=\"color: #808000\"><strong><a style=\"color: #808000\" href=\"https:\/\/whatsapp.com\/channel\/0029VaBQlmUEVccJs6JPNB0N\">Clique aqui<\/a><\/strong>\u00a0<\/span>para participar e fique por dentro de tudo o que \u00e9 destaque na nossa universidade.","post_title":"Editora Unicentro participa de encontro nacional de editoras universit\u00e1rias na Universidade Federal da Bahia","post_excerpt":"Evento anual da Abeu re\u00fane representantes de mais de 130 editoras para debater inova\u00e7\u00e3o, leitura e os desafios da edi\u00e7\u00e3o acad\u00eamica no Brasil.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"editora-unicentro-participa-de-encontro-nacional-de-editoras-universitarias-na-universidade-federal-da-bahia","to_ping":"","pinged":"","post_modified":"2026-05-13 11:44:18","post_modified_gmt":"2026-05-13 14:44:18","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www3.unicentro.br\/noticias\/?p=51863","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw","mobiconnector_feature_image":{"id":51867,"alt_text":"","caption":"","description":"","media_type":"image","post":51863,"source_url":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp_Image_2026_05_12_at_08_48_51_6a031c781b884-1.jpeg","mobiconnector_small":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_medium":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_x_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/"}},{"ID":51848,"post_author":"578","post_date":"2026-05-12T20:56:19","post_date_gmt":"2026-05-12T23:56:19","post_content":"<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Estudante do 3\u00ba ano do curso de Educa\u00e7\u00e3o F\u00edsica do C\u00e2mpus de Irati da Universidade Estadual do Centro-Oeste (Unicentro), Matheus Siebre tem se destacado no cen\u00e1rio nacional do boxe na categoria meio-pesado amador. O pugilista acumula conquistas regionais e estaduais, incluindo t\u00edtulos em competi\u00e7\u00f5es vinculadas \u00e0 World Boxing Association (WBA), a mais antiga entidade do boxe mundial.<\/span><\/p>\r\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">O \u00faltimo resultado expressivo foi obtido no s\u00e1bado (9), na 4\u00aa edi\u00e7\u00e3o do WBA Future of Brazilian Boxing. Na ocasi\u00e3o, Siebre derrotou Leonardo da Luz Rodrigues, o que o levou \u00e0 14\u00aa posi\u00e7\u00e3o entre os brasileiros da sua divis\u00e3o, segundo dados da plataforma internacional BoxRec.<\/span><\/p>\r\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">A vit\u00f3ria veio ap\u00f3s uma prepara\u00e7\u00e3o marcada por limita\u00e7\u00f5es f\u00edsicas. Na semana anterior ao combate, o atleta sofreu les\u00f5es no joelho e no pulso direito. Durante o combate, tamb\u00e9m machucou o pulso esquerdo. \u201cEntrei com duas les\u00f5es e sa\u00ed com tr\u00eas. Mesmo assim, consegui abrir duas contagens no meu advers\u00e1rio, uma no segundo e outra no terceiro round, e vencer por decis\u00e3o un\u00e2nime dos ju\u00edzes\u201d, relata.<\/span><\/p>\r\n\r\n\r\n[caption id=\"attachment_51850\" align=\"alignright\" width=\"287\"]<img class=\"wpa-warning wpa-image-missing-alt wp-image-51850\" src=\"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-12-at-14.15.36-1.jpeg\" alt=\"\" width=\"287\" height=\"430\" data-warning=\"Texto alternativo ausente\" \/> <em>Estudante do C\u00e2mpus de Irati, Matheus Siebre ocupa a 14\u00aa posi\u00e7\u00e3o no ranking nacional entre os meio-pesados amadores. (Foto: Revista 1\u00ba Round)<\/em>[\/caption]\r\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Realizado em S\u00e3o Jos\u00e9 dos Pinhais, na regi\u00e3o metropolitana de Curitiba, o torneio supervisionado pelo Conselho Nacional de Boxe (CNB) \u00e9 voltado \u00e0 descoberta e ao desenvolvimento de novos talentos, com participantes de diferentes regi\u00f5es do pa\u00eds. O Paran\u00e1 \u00e9 atualmente o \u00fanico estado brasileiro autorizado pela WBA a sediar a competi\u00e7\u00e3o. \u201cTivemos grandes lutas em um grande evento, e com isso o futuro do boxe est\u00e1 cada vez melhor\u201d, comenta o presidente da Federa\u00e7\u00e3o Paranaense de Boxe, Macaris do Livramento, campe\u00e3o mundial pela World Boxing Commission na d\u00e9cada de 1990.<\/span><\/p>\r\n\r\n<div class=\"wp-block-image\"><\/div>\r\n<p style=\"text-align: justify\"><b>Entre os ringues e a sala de aula<\/b><\/p>\r\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Como conta Matheus, a trajet\u00f3ria no esporte come\u00e7ou aos 11 anos, quando precisou enfrentar o <\/span><i><span style=\"font-weight: 400\">bullying<\/span><\/i><span style=\"font-weight: 400\">. \u201cEu era muito magro e tinha alguns \u2018amigos\u2019 que falavam bastante da minha apar\u00eancia e dos meus dentes, principalmente, at\u00e9 come\u00e7arem a fazer brincadeiras envolvendo agress\u00f5es. Para n\u00e3o preocupar minha fam\u00edlia, fui para uma escola de lutas para aprender a me defender, e desde ent\u00e3o surgiu minha paix\u00e3o pela luta\u201d, relembra.<\/span><\/p>\r\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Com o passar dos anos, o que come\u00e7ou como uma forma de defesa pessoal se transformou em um projeto de vida. Nesse percurso, a gradua\u00e7\u00e3o ofertada pela Unicentro se mostrou uma escolha importante. Segundo o boxeador, os conhecimentos adquiridos no curso de Educa\u00e7\u00e3o F\u00edsica contribuem diretamente para o desempenho nos treinamentos e competi\u00e7\u00f5es.<\/span><\/p>\r\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">\u201cO ensino que tenho na Unicentro, como estudante de Educa\u00e7\u00e3o F\u00edsica, com certeza me ajuda muito com os meus treinos. A forma\u00e7\u00e3o \u00e9 de alto n\u00edvel e isso agrega bastante, porque hoje consigo entender exatamente o que um atleta precisa fazer desde o come\u00e7o at\u00e9 o fim da prepara\u00e7\u00e3o f\u00edsica para a luta\u201d, afirma.<\/span><\/p>\r\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Para a chefe do Departamento de Educa\u00e7\u00e3o (Deduf\/I), professora Debora Gomes, o sucesso esportivo de Matheus \u00e9 uma vit\u00f3ria pessoal, mas tamb\u00e9m um reflexo do compromisso e da resili\u00eancia que o curso busca cultivar em seus alunos.<\/span><\/p>\r\n<span style=\"font-weight: 400\">\u201c\u00c9 de suma import\u00e2ncia, pois materializa a indissociabilidade entre a forma\u00e7\u00e3o acad\u00eamica e o esporte de alto rendimento. Ele exemplifica o desafio di\u00e1rio de muitos de nossos estudantes que precisam equilibrar trabalho, estudos e treinamentos rigorosos. Sua trajet\u00f3ria refor\u00e7a o papel da nossa universidade em apoiar e formar profissionais que compreendem a Educa\u00e7\u00e3o F\u00edsica em sua m\u00e1xima excel\u00eancia\u201d, pontua a docente. <\/span>\r\n\r\n<span style=\"font-weight: 400\">\u201cMatheus n\u00e3o leva apenas as luvas para o ringue, leva consigo o nome da Unicentro\u201d, ressalta a chefe do Deduf.<\/span>\r\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Com a nova coloca\u00e7\u00e3o no ranking, Matheus projeta seguir crescendo no cen\u00e1rio nacional da modalidade. \u201cMeu plano \u00e9 subir cada vez mais no ranking, chegar ao top 1 brasileiro e, se Deus permitir, ser campe\u00e3o do mundo um dia\u201d, destaca o acad\u00eamico.<\/span><\/p>\r\n<p style=\"text-align: justify\"><span style=\"font-size: 8pt\"><i><span style=\"font-weight: 400\">Texto: Wyllian Correa\r\nFoto: Revista 1\u00ba Round<\/span><\/i><\/span><\/p>\r\n\r\n\r\n<hr \/>\r\n<p style=\"text-align: justify\"><span style=\"color: #808000\"><strong>Voc\u00ea j\u00e1 conhece o canal de transmiss\u00e3o da Unicentro no WhatsApp?<\/strong><\/span><\/p>\r\n<p style=\"text-align: justify\">L\u00e1, voc\u00ea encontra not\u00edcias fresquinhas e em primeira m\u00e3o, al\u00e9m de comunicados oficiais, eventos, conquistas da galera e muito mais!\u00a0<span style=\"color: #808000\"><strong><a style=\"color: #808000\" href=\"https:\/\/whatsapp.com\/channel\/0029VaBQlmUEVccJs6JPNB0N\">Clique aqui<\/a><\/strong>\u00a0<\/span>para participar e fique por dentro de tudo o que \u00e9 destaque na nossa universidade.<\/p>\r\n&nbsp;\r\n\r\n&nbsp;","post_title":"Acad\u00eamico de Educa\u00e7\u00e3o F\u00edsica da Unicentro ganha destaque no boxe nacional","post_excerpt":"Estudante do C\u00e2mpus de Irati, Matheus Siebre ocupa a 14\u00aa posi\u00e7\u00e3o no ranking nacional entre os meio-pesados amadores.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"academico-de-educacao-fisica-da-unicentro-ganha-destaque-no-boxe-nacional","to_ping":"","pinged":"","post_modified":"2026-05-12 21:14:30","post_modified_gmt":"2026-05-13 00:14:30","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www3.unicentro.br\/noticias\/?p=51848","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw","mobiconnector_feature_image":{"id":51851,"alt_text":"","caption":"","description":"","media_type":"image","post":51848,"source_url":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-12-at-14.15.36.jpeg","mobiconnector_small":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_medium":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_x_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/"}},{"ID":51826,"post_author":"255","post_date":"2026-05-12T11:28:40","post_date_gmt":"2026-05-12T14:28:40","post_content":"[vc_row][vc_column][vc_column_text css=\"\"]\r\n<p style=\"text-align: justify\" align=\"justify\">O Departamento de Direito da Universidade Estadual do Centro-Oeste (Unicentro) promoveu, nesta ter\u00e7a-feira (12), a aula inaugural intitulada \u201cA evolu\u00e7\u00e3o da propaganda pol\u00edtica e sua moldura legal\u201d, proferida pelo juiz de Direito Rafhael Wasserman, do Tribunal de Justi\u00e7a do Estado do Paran\u00e1.<\/p>\r\n<p style=\"text-align: justify\" align=\"justify\">A conversa com os estudantes abordou a propaganda eleitoral, limites legais e os desafios de fiscaliza\u00e7\u00e3o. A escolha do tema, explica o chefe do Departamento de Direito, Luiz Verg\u00edlio Dalla Rosa, se deve ao per\u00edodo eleitoral e aos impactos das plataformas digitais na dissemina\u00e7\u00e3o de conte\u00fados pol\u00edticos. \u201cNosso convidado aborda, justamente, a introdu\u00e7\u00e3o e a discuss\u00e3o sobre o uso da propaganda eleitoral, os limites, as dificuldades de controle em era digital, em era de rede social. Buscamos fazer essa ponte entre o mercado, a realidade acad\u00eamica e a profiss\u00e3o do Direito, sempre antenados com a realidade social atual\u201d, destaca.<\/p>\r\n<p style=\"text-align: justify\" align=\"justify\">Na palestra, o juiz Rafhael Wasserman dividiu os apontamentos em cinco eixos: a Justi\u00e7a Eleitoral; o que \u00e9 a propaganda eleitoral; quando a propaganda eleitoral pode ser feita; as esp\u00e9cies de propagandas eleitorais; e os exemplos de propagandas irregulares e o que pode ser feito nesses casos. \u201cA ideia \u00e9 que os alunos tomem conhecimento e passem a ter mais no\u00e7\u00e3o de como a Justi\u00e7a Eleitoral funciona, qual \u00e9 o regramento, com uma vis\u00e3o mais cr\u00edtica da propaganda, para verificar se o que est\u00e1 sendo feito \u00e9 regular ou n\u00e3o\u201d, ressalta. \u201cTamb\u00e9m, para que eles possam agir de acordo com uma vis\u00e3o mais cidad\u00e3 e que possam participar mais ativamente desse processo\u201d, acrescenta.<\/p>\r\n[gallery link=\"file\" size=\"large\" ids=\"51842,51838,51841\"]\r\n<p style=\"text-align: justify\" align=\"justify\">O palestrante tamb\u00e9m destacou a import\u00e2ncia da participa\u00e7\u00e3o da sociedade na fiscaliza\u00e7\u00e3o do processo eleitoral. \u201cUma das ideias tamb\u00e9m \u00e9 que, a partir dessa palestra e de outras comunica\u00e7\u00f5es que v\u00e3o acontecer ao longo desse ano, aumente a no\u00e7\u00e3o de que esses estudantes, enquanto profissionais, t\u00eam o papel fundamental de capilarizar a atua\u00e7\u00e3o da justi\u00e7a eleitoral\u201d, refor\u00e7a.<\/p>\r\n<p style=\"text-align: justify\" align=\"justify\">Para a estudante do quinto per\u00edodo, Maria Eduarda Lima, a atividade amplia a compreens\u00e3o sobre as possibilidades de atua\u00e7\u00e3o profissional e contribui de forma significativa para a forma\u00e7\u00e3o acad\u00eamica. \u201cAcho que agrega muito na nossa forma\u00e7\u00e3o por nos permitir conhecer os diversos tipos de mercado em que podemos atuar. Tamb\u00e9m agrega no conhecimento que estamos tendo, al\u00e9m do que j\u00e1 \u00e9 experi\u00eancia durante o curso\u201d, comenta.<\/p>\r\n<p style=\"text-align: justify\" align=\"justify\">Sobre a relev\u00e2ncia do tema em ano eleitoral, a acad\u00eamica destacou como o conhecimento pode diminuir o impacto da desinforma\u00e7\u00e3o. \u201c\u00c9 de suma import\u00e2ncia, principalmente devido a grande onda de <i>fake news<\/i> que estamos tendo, com muitos abusos eleitorais por parte dos pr\u00f3prios candidatos e a popula\u00e7\u00e3o tamb\u00e9m acaba indo nessa onda. \u00c9 muito importante termos essa consci\u00eancia do exerc\u00edcio da nossa cidadania\u201d, avalia.<\/p>\r\n[gallery link=\"file\" size=\"large\" ids=\"51840,51837,51843\"]\r\n<p style=\"text-align: justify\"><span style=\"font-size: 8pt\"><em>Por Ma\u00edra Machado<\/em><\/span><\/p>\r\n\r\n\r\n<hr \/>\r\n<p style=\"text-align: justify\"><span style=\"color: #808000\"><strong>Voc\u00ea j\u00e1 conhece o canal de transmiss\u00e3o da Unicentro no WhatsApp?<\/strong><\/span><\/p>\r\n<p style=\"text-align: justify\">L\u00e1, voc\u00ea encontra not\u00edcias fresquinhas e em primeira m\u00e3o, al\u00e9m de comunicados oficiais, eventos, conquistas da galera e muito mais!\u00a0<span style=\"color: #808000\"><strong><a style=\"color: #808000\" href=\"https:\/\/whatsapp.com\/channel\/0029VaBQlmUEVccJs6JPNB0N\">Clique aqui<\/a><\/strong>\u00a0<\/span>para participar e fique por dentro de tudo o que \u00e9 destaque na nossa universidade.<\/p>\r\n[\/vc_column_text][\/vc_column][\/vc_row]","post_title":"Aula inaugural do curso de Direito aborda aspectos das propagandas pol\u00edticas","post_excerpt":"Ministrada pelo juiz Rafhael Wasserman, a palestra discutiu os limites legais da propaganda pol\u00edtica e a atua\u00e7\u00e3o da Justi\u00e7a Eleitoral","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"aula-inaugural-do-curso-de-direito-aborda-aspectos-das-propagandas-politicas","to_ping":"","pinged":"","post_modified":"2026-05-13 10:31:19","post_modified_gmt":"2026-05-13 13:31:19","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www3.unicentro.br\/noticias\/?p=51826","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw","mobiconnector_feature_image":{"id":51846,"alt_text":"","caption":"","description":"","media_type":"image","post":51826,"source_url":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/DSC_3001.jpg","mobiconnector_small":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_medium":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_x_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/"}},{"ID":51820,"post_author":"9","post_date":"2026-05-12T11:16:20","post_date_gmt":"2026-05-12T14:16:20","post_content":"&nbsp;\r\n<h3 style=\"text-align: center\" data-start=\"1775\" data-end=\"1789\"><sup><em>Selecionada no programa \"Talentos Paran\u00e1 no Mundo\", acad\u00eamica embarca para sua primeira experi\u00eancia internacional<\/em><\/sup><\/h3>\r\n\r\n<hr \/>\r\n<p style=\"text-align: justify\" data-start=\"240\" data-end=\"710\">Uma oportunidade transformadora est\u00e1 prestes a marcar a trajet\u00f3ria acad\u00eamica de Maria Clara Turkot, de 19 anos, estudante do curso de Ci\u00eancia da Computa\u00e7\u00e3o da Universidade Estadual do Centro-Oeste (Unicentro). A universit\u00e1ria garantiu uma das dez vagas destinadas a estudantes paranaenses no programa \"Talentos Paran\u00e1 no Mundo\" para uma experi\u00eancia de imers\u00e3o nos Estados Unidos, ap\u00f3s a divulga\u00e7\u00e3o do resultado final do edital da Secretaria da Ci\u00eancia, Tecnologia e Ensino Superior (Seti).<\/p>\r\n<p style=\"text-align: justify\" data-start=\"712\" data-end=\"1051\">A iniciativa do Governo do Paran\u00e1 busca promover a internacionaliza\u00e7\u00e3o do ensino superior estadual, conectando estudantes a um dos principais centros educacionais e culturais do mundo. Para Maria Clara, o an\u00fancio da aprova\u00e7\u00e3o representa n\u00e3o apenas a realiza\u00e7\u00e3o de um sonho, mas o in\u00edcio de um novo cap\u00edtulo em sua forma\u00e7\u00e3o profissional. O interc\u00e2mbio ser\u00e1 na Universidade da Cidade de Nova York (Cuny), com atividades letivas na Faculdade de Staten Island (CSI). O interc\u00e2mbio est\u00e1 previsto para ocorrer entre os dias 28 de junho e 8 de agosto.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"1053\" data-end=\"1338\">Esta ser\u00e1 a primeira vez que a estudante ter\u00e1 a oportunidade de estudar fora do pa\u00eds. O desejo de expandir horizontes foi o que a motivou a participar do processo seletivo. \"Ao ver que eu poderia me inscrever, n\u00e3o pensei duas vezes para tentar mergulhar de cabe\u00e7a nessa oportunidade\", conta.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"1340\" data-end=\"1839\">O interc\u00e2mbio em solo americano promete ir al\u00e9m das salas de aula. Embora o aprendizado da l\u00edngua inglesa e o contato com sua \u00e1rea de estudo em um polo global sejam prioridades, a viv\u00eancia urbana e social de Nova York desperta grande expectativa. \u201cAl\u00e9m de conhecer e passear pelos pontos tur\u00edsticos, espero tamb\u00e9m poder aprender muito sobre a cultura de uma cidade t\u00e3o grande como Nova York, como tudo funciona t\u00e3o bem l\u00e1. Al\u00e9m disso, poder ter aulas de ingl\u00eas, e ouvir sobre a minha \u00e1rea de estudo nesse polo t\u00e3o importante\", afirma a estudante.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"1340\" data-end=\"1839\">Maria planeja absorver toda a bagagem de conhecimento, trazendo refer\u00eancias que possam ser aplicadas em seus projetos dentro da Unicentro e em futuras iniciativas autorais. Para ela, o interc\u00e2mbio funciona como um divisor de \u00e1guas na carreira \"Acredito que agregue muito no meu curr\u00edculo, por ser uma experi\u00eancia que poucas pessoas conseguem, \u00e9 um diferencial muito grande\".<\/p>\r\n<p style=\"text-align: justify\">A expectativa \u00e9 que o contato com o ensino e o mercado de trabalho no exterior traga uma nova perspectiva sobre a realidade brasileira. \"L\u00e1 \u00e9 algo muito maior, ent\u00e3o espero voltar com uma vis\u00e3o muito aberta de tudo e poder crescer mais aqui\", completa.<\/p>\r\n&nbsp;\r\n\r\n[caption id=\"attachment_51828\" align=\"aligncenter\" width=\"650\"]<img class=\"wpa-warning wpa-image-missing-alt wp-image-51828\" src=\"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/CSI_horizontal.jpg\" alt=\"\" width=\"650\" height=\"414\" data-warning=\"Texto alternativo ausente\" \/> As atividades letivas ser\u00e3o na Faculdade de Staten Island, da Universidade da Cidade de Nova York.[\/caption]\r\n\r\n&nbsp;\r\n\r\n<em>Por Evelyne Dutra, com supervis\u00e3o de Giovani Ciquelero<\/em>\r\n\r\n<hr \/>\r\n\r\n<span style=\"color: #808000\"><strong>Voc\u00ea j\u00e1 conhece o canal de transmiss\u00e3o da Unicentro no WhatsApp?<\/strong><\/span>\r\n\r\nL\u00e1, voc\u00ea encontra not\u00edcias fresquinhas e em primeira m\u00e3o, al\u00e9m de comunicados oficiais, eventos, conquistas da galera e muito mais!\u00a0<span style=\"color: #808000\"><strong><a style=\"color: #808000\" href=\"https:\/\/whatsapp.com\/channel\/0029VaBQlmUEVccJs6JPNB0N\">Clique aqui<\/a><\/strong>\u00a0<\/span>para participar e fique por dentro de tudo o que \u00e9 destaque na nossa universidade.","post_title":"Estudante da Unicentro conquista vaga para interc\u00e2mbio em Nova York","post_excerpt":"Selecionada no programa \"Talentos Paran\u00e1 no Mundo\", acad\u00eamica embarca para sua primeira experi\u00eancia internacional.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"estudante-da-unicentro-conquista-vaga-para-intercambio-em-nova-york","to_ping":"","pinged":"","post_modified":"2026-05-12 11:16:20","post_modified_gmt":"2026-05-12 14:16:20","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www3.unicentro.br\/noticias\/?p=51820","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw","mobiconnector_feature_image":{"id":51833,"alt_text":"","caption":"","description":"","media_type":"image","post":51820,"source_url":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-11-at-14.55.32-1.jpeg","mobiconnector_small":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_medium":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_x_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/"}},{"ID":51812,"post_author":"9","post_date":"2026-05-12T10:25:59","post_date_gmt":"2026-05-12T13:25:59","post_content":"&nbsp;\r\n<h3 style=\"text-align: center\" data-start=\"1775\" data-end=\"1789\"><sup><em>Evento ocorre de 25 a 29 de maio na Unicentro, com inscri\u00e7\u00f5es abertas para apresentadores, ouvintes, pesquisadores, estudantes e professores<\/em><\/sup><\/h3>\r\n<p style=\"text-align: justify\" data-start=\"83\" data-end=\"491\">A <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Universidade Estadual do Centro-Oeste (Unicentro)<\/span><\/span> realiza, entre os dias 25 e 29 de maio, o 4\u00ba Col\u00f3quio Internacional de Estudos da Linguagem e o 1\u00ba Col\u00f3quio de Museus e Memorial\u00edstica. Com o tema \u201cTumultos, Democracia, Revolu\u00e7\u00f5es e Contrarrevolu\u00e7\u00f5es\u201d, o evento prop\u00f5e reflex\u00f5es sobre o papel da linguagem, da mem\u00f3ria e da hist\u00f3ria diante dos atuais desafios pol\u00edticos e sociais.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"493\" data-end=\"861\">De acordo com uma das organizadoras do evento, professora <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Maria Cleci Venturini<\/span><\/span>, a escolha da tem\u00e1tica surge da observa\u00e7\u00e3o da \"fragilidade da nossa democracia\" e da necessidade de di\u00e1logo com vizinhos latino-americanos, como a Argentina e o Uruguai, que enfrentam desafios semelhantes no campo dos direitos humanos e das liberdades individuais.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"863\" data-end=\"1266\">Para a pesquisadora, a atua\u00e7\u00e3o acad\u00eamica e profissional exige um compromisso inegoci\u00e1vel com a realidade social. \"Para voc\u00ea ser um professor, um profissional da \u00e1rea da linguagem, voc\u00ea precisa estar sempre atento \u00e0 quest\u00e3o das lutas sociais. N\u00e3o \u00e9 ser contra tudo, mas \u00e9 saber do que voc\u00ea est\u00e1 falando e nos interessarmos pela resist\u00eancia tamb\u00e9m\", destaca a docente do Departamento de Letras de Guarapuava.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"1268\" data-end=\"1457\">Segundo a docente, o col\u00f3quio tamb\u00e9m busca incentivar a produ\u00e7\u00e3o do conhecimento e promover discuss\u00f5es que combatam processos de aliena\u00e7\u00e3o potencializados pelas tecnologias e redes sociais. O evento est\u00e1 com chamadas abertas para submiss\u00e3o de resumos expandidos. Podem participar docentes e pesquisadores de institui\u00e7\u00f5es de ensino superior, estudantes de gradua\u00e7\u00e3o e p\u00f3s-gradua\u00e7\u00e3o e profissionais da Educa\u00e7\u00e3o B\u00e1sica, especialmente com relatos de experi\u00eancia e pr\u00e1ticas pedag\u00f3gicas. O col\u00f3quio contar\u00e1 com a presen\u00e7a de pesquisadoras de renome, como a Elvira Arnoux e Alma Bol\u00f3n, refer\u00eancias nos estudos da linguagem e quest\u00f5es sociais.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"1804\" data-end=\"2202\">As inscri\u00e7\u00f5es para apresentadores seguem <strong>at\u00e9 15 de maio<\/strong>, com taxas de R$ 20 para estudantes de gradua\u00e7\u00e3o e R$ 40 para estudantes de p\u00f3s-gradua\u00e7\u00e3o e professores da Educa\u00e7\u00e3o B\u00e1sica. Para professores universit\u00e1rios, a inscri\u00e7\u00e3o custa R$ 60. J\u00e1 as inscri\u00e7\u00f5es para ouvintes seguem <strong>at\u00e9 21 de maio<\/strong>, com taxa de R$ 20. Conferencistas e participantes de mesas ou palestras podem se inscrever <strong>at\u00e9 25 de maio<\/strong>.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"2577\" data-end=\"2800\" data-is-last-node=\"\" data-is-only-node=\"\">As submiss\u00f5es e inscri\u00e7\u00f5es devem ser feitas no <a class=\"decorated-link\" href=\"https:\/\/evento.unicentro.br\/site\/museus_coloquio_2026\/2026\/1?utm_source=chatgpt.com\" target=\"_blank\" rel=\"noopener\" data-start=\"2690\" data-end=\"2799\"><strong>site do evento<\/strong><\/a>.<\/p>\r\n\r\n<div class=\"wp-block-image\"><img class=\"wpa-warning wpa-image-missing-alt alignnone size-full wp-image-51814\" src=\"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/30_03_2026_event_1053345340.jpg\" alt=\"\" width=\"1920\" height=\"270\" data-warning=\"Texto alternativo ausente\" \/><\/div>\r\n&nbsp;\r\n\r\n<em>Por Evelyne Dutra, com supervis\u00e3o de Giovani Ciquelero<\/em>\r\n\r\n<hr \/>\r\n\r\n<span style=\"color: #808000\"><strong>Voc\u00ea j\u00e1 conhece o canal de transmiss\u00e3o da Unicentro no WhatsApp?<\/strong><\/span>\r\n\r\nL\u00e1, voc\u00ea encontra not\u00edcias fresquinhas e em primeira m\u00e3o, al\u00e9m de comunicados oficiais, eventos, conquistas da galera e muito mais!\u00a0<span style=\"color: #808000\"><strong><a style=\"color: #808000\" href=\"https:\/\/whatsapp.com\/channel\/0029VaBQlmUEVccJs6JPNB0N\">Clique aqui<\/a><\/strong>\u00a0<\/span>para participar e fique por dentro de tudo o que \u00e9 destaque na nossa universidade.","post_title":"Unicentro promove col\u00f3quio internacional sobre democracia, linguagem e mem\u00f3ria","post_excerpt":"Evento ocorre de 25 a 29 de maio na Unicentro, com inscri\u00e7\u00f5es abertas para apresentadores, ouvintes, pesquisadores, estudantes e professores.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"unicentro-promove-coloquio-internacional-sobre-democracia-linguagem-e-memoria","to_ping":"","pinged":"","post_modified":"2026-05-12 10:25:59","post_modified_gmt":"2026-05-12 13:25:59","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www3.unicentro.br\/noticias\/?p=51812","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw","mobiconnector_feature_image":{"id":51818,"alt_text":"","caption":"","description":"","media_type":"image","post":51812,"source_url":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/coloquio-e1778592315845.jpg","mobiconnector_small":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_medium":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_x_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/"}},{"ID":51803,"post_author":"9","post_date":"2026-05-11T05:04:50","post_date_gmt":"2026-05-11T08:04:50","post_content":"&nbsp;\r\n<h3 style=\"text-align: center\" data-start=\"1775\" data-end=\"1789\"><sup><em>O evento prop\u00f5e debates sobre o tema \u201cProjeto \u00e9tico-pol\u00edtico e a rela\u00e7\u00e3o com os projetos societ\u00e1rios\u201d, nos dias 14 e 15 de maio<\/em><\/sup><\/h3>\r\n\r\n<hr \/>\r\n<p style=\"text-align: justify\" data-start=\"114\" data-end=\"484\">O Departamento de Servi\u00e7o Social da Universidade Estadual do Centro-Oeste (Unicentro) realiza, nos dias 14 e 15 de maio, o 16\u00ba F\u00f3rum de Est\u00e1gio Supervisionado em Servi\u00e7o Social, no C\u00e2mpus Santa Cruz. O evento prop\u00f5e debates sobre o tema \u201cProjeto \u00e9tico-pol\u00edtico e a rela\u00e7\u00e3o com os projetos societ\u00e1rios\u201d.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"486\" data-end=\"728\">A programa\u00e7\u00e3o inicia no dia 14 de maio, com uma palestra magna ministrada pela professora Ros\u00e2ngela Bujokas de Siqueira, da Universidade Estadual de Ponta Grossa (UEPG). A atividade acontece das 19h \u00e0s 22h, no miniaudit\u00f3rio do c\u00e2mpus.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"730\" data-end=\"1007\">No segundo dia de evento, ser\u00e3o promovidas quatro oficinas simult\u00e2neas com discuss\u00f5es sobre supervis\u00e3o de est\u00e1gio, participa\u00e7\u00e3o da popula\u00e7\u00e3o nos servi\u00e7os, acesso a direitos e conselhos de direitos. As atividades ocorrem no miniaudit\u00f3rio e nos blocos R e Q do C\u00e2mpus Santa Cruz.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"1009\" data-end=\"1234\">De acordo com a organiza\u00e7\u00e3o, o f\u00f3rum busca fortalecer os espa\u00e7os de reflex\u00e3o e di\u00e1logo entre estudantes, professores, supervisores e profissionais da \u00e1rea, aproximando a forma\u00e7\u00e3o acad\u00eamica das demandas sociais contempor\u00e2neas.<\/p>\r\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">As inscri\u00e7\u00f5es devem ser realizadas pelo formul\u00e1rio do evento, dispon\u00edvel no site <strong><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdbYRU99UAgd4X8ZNUrJMw93Sl_BUM6hN8V_jA1qFj-NVA19A\/viewform\" target=\"_blank\" rel=\"noopener\">unicentro.br\/forumss<\/a><\/strong>.<\/span><\/p>\r\n[gallery columns=\"2\" size=\"medium\" ids=\"51804,51805\"]","post_title":"Departamento de Servi\u00e7o Social promove f\u00f3rum sobre forma\u00e7\u00e3o profissional e projetos societ\u00e1rios","post_excerpt":"O evento prop\u00f5e debates sobre o tema \u201cProjeto \u00e9tico-pol\u00edtico e a rela\u00e7\u00e3o com os projetos societ\u00e1rios\u201d, nos dias 14 e 15 de maio.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"departamento-de-servico-social-promove-forum-sobre-formacao-profissional-e-projetos-societarios","to_ping":"","pinged":"","post_modified":"2026-05-11 05:04:50","post_modified_gmt":"2026-05-11 08:04:50","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www3.unicentro.br\/noticias\/?p=51803","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw","mobiconnector_feature_image":{"id":51809,"alt_text":"","caption":"","description":"","media_type":"image","post":51803,"source_url":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/SaveClip.App_689008046_1393151486183025_5559873268620242453_n-1-e1778486555781.jpg","mobiconnector_small":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_medium":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_x_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/"}},{"ID":51795,"post_author":"9","post_date":"2026-05-10T22:18:04","post_date_gmt":"2026-05-11T01:18:04","post_content":"&nbsp;\r\n<h3 style=\"text-align: center\" data-start=\"1775\" data-end=\"1789\"><sup><em>Iniciativa visa acolher estudantes estrangeiros e facilitar a integra\u00e7\u00e3o na cidade e c\u00e2mpus universit\u00e1rio<\/em><\/sup><\/h3>\r\n\r\n<hr \/>\r\n<p style=\"text-align: justify\">Est\u00e3o abertas as inscri\u00e7\u00f5es para o programa \u201cAmigos da Internacionaliza\u00e7\u00e3o\u201d, iniciativa organizada pela Coordenadoria de Rela\u00e7\u00f5es Internacionais (Coori) da Universidade Estadual do Centro-Oeste, que visa promover o acolhimento de estudantes estrangeiros e facilitar sua integra\u00e7\u00e3o. O projeto convida membros da comunidade universit\u00e1ria a atuarem como \u201cpadrinhos\u201d e \u201cmadrinhas\u201d, auxiliando os alunos rec\u00e9m-chegados na adapta\u00e7\u00e3o ao pa\u00eds, \u00e0 universidade e \u00e0 rotina acad\u00eamica.<\/p>\r\n<p style=\"text-align: justify\">Al\u00e9m do acolhimento, o programa busca incentivar a pr\u00e1tica de idiomas, a troca cultural e a conviv\u00eancia intercultural entre brasileiros e estudantes internacionais. Segundo o diretor de Acordos de Coopera\u00e7\u00e3o e Mobilidade Internacional, Adriano Machado, o n\u00famero de alunos internacionais tem crescido e o programa visa proporcionar a recep\u00e7\u00e3o em atividades culturais, esportivas, acad\u00eamicas e sociais. Al\u00e9m dessa integra\u00e7\u00e3o, h\u00e1 casos de vulnerabilidade social em que o grupo de colaboradores \u00e9 essencial para apoiar os rec\u00e9m chegados.<\/p>\r\n<p style=\"text-align: justify\">\u201cMuitas vezes s\u00e3o coisas simples para quem est\u00e1 ajudando, para quem est\u00e1 colaborando, para quem \u00e9 amigo da internacionaliza\u00e7\u00e3o, mas para quem est\u00e1 recebendo acaba sendo fundamental, desde a colabora\u00e7\u00e3o com alguma alimenta\u00e7\u00e3o, passeio, atividade, que podem ser simples, mas s\u00e3o enriquecedoras para quem est\u00e1 recebendo\u201d, destacou.<\/p>\r\n<p style=\"text-align: justify\">De acordo com Adriano, ter uma rede de apoio \u00e9 fundamental para integr\u00e1-los no corpo universit\u00e1rio. \u201cA nossa expectativa \u00e9 muito grande, para que possamos fortalecer essa rede e recepcionarmos da melhor forma poss\u00edvel nossos alunos internacionais\u201d, afirmou.<\/p>\r\n<p style=\"text-align: justify\">Os participantes inscritos no programa n\u00e3o assumem compromisso de hospedagem dos intercambistas. O cadastro serve para reunir pessoas interessadas em colaborar com o acolhimento e integra\u00e7\u00e3o dos estudantes. As inscri\u00e7\u00f5es podem ser feitas pelo <strong><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSe01iKrrKcUKzFuhR_G5H3jrQIfpkto8rb9wW4SX8tFJ5oFjQ\/viewform\" target=\"_blank\" rel=\"noopener\">formul\u00e1rio disponibilizado pela Coori<\/a><\/strong>.<\/p>\r\n[gallery columns=\"2\" size=\"medium\" ids=\"51796,51797\"]\r\n\r\n<em>Por Milena Kammer, com supervis\u00e3o de Giovani Ciquelero<\/em>\r\n\r\n<hr \/>\r\n\r\n<span style=\"color: #808000\"><strong>Voc\u00ea j\u00e1 conhece o canal de transmiss\u00e3o da Unicentro no WhatsApp?<\/strong><\/span>\r\n\r\nL\u00e1, voc\u00ea encontra not\u00edcias fresquinhas e em primeira m\u00e3o, al\u00e9m de comunicados oficiais, eventos, conquistas da galera e muito mais!\u00a0<span style=\"color: #808000\"><strong><a style=\"color: #808000\" href=\"https:\/\/whatsapp.com\/channel\/0029VaBQlmUEVccJs6JPNB0N\">Clique aqui<\/a><\/strong>\u00a0<\/span>para participar e fique por dentro de tudo o que \u00e9 destaque na nossa universidade.","post_title":"Programa busca fortalecer acolhimento de estudantes estrangeiros em Guarapuava","post_excerpt":"A iniciativa \u201cAmigos da Internacionaliza\u00e7\u00e3o\u201d \u00e9 promovida pela Coordenadoria de Rela\u00e7\u00f5es Internacionais da Universidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"programa-busca-fortalecer-acolhimento-de-estudantes-estrangeiros-em-guarapuava","to_ping":"","pinged":"","post_modified":"2026-05-10 22:18:04","post_modified_gmt":"2026-05-11 01:18:04","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www3.unicentro.br\/noticias\/?p=51795","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw","mobiconnector_feature_image":{"id":51801,"alt_text":"","caption":"","description":"","media_type":"image","post":51795,"source_url":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/SaveClip.App_690630576_1395764909255016_1467881746515188097_n-1-e1778462115780.jpg","mobiconnector_small":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_medium":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_x_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/"}},{"ID":51788,"post_author":"9","post_date":"2026-05-09T13:03:22","post_date_gmt":"2026-05-09T16:03:22","post_content":"&nbsp;\r\n<h3 style=\"text-align: center\" data-start=\"1775\" data-end=\"1789\"><sup><em>Com investimento de R$ 2,5 milh\u00f5es, moradia estudantil est\u00e1 com mais da metade das obras conclu\u00eddas<\/em><\/sup><\/h3>\r\n\r\n<hr \/>\r\n<p style=\"text-align: justify\">A Universidade Estadual do Centro-Oeste (Unicentro) recebeu, nesta sexta-feira (8), a visita do deputado federal Aliel Machado. Durante a agenda, o parlamentar acompanhou o andamento das obras da Casa do Estudante no C\u00e2mpus Cedeteg, em Guarapuava, iniciativa voltada \u00e0 perman\u00eancia acad\u00eamica e ao apoio de universit\u00e1rios em situa\u00e7\u00e3o de vulnerabilidade social.<\/p>\r\n<p style=\"text-align: justify\">A obra recebeu R$ 1 milh\u00e3o por meio de emenda parlamentar destinada pelo deputado. O investimento total \u00e9 de aproximadamente R$ 2,5 milh\u00f5es, com recursos viabilizados pela Secretaria da Ci\u00eancia, Tecnologia e Ensino Superior (Seti) e pelo Fundo Nacional de Desenvolvimento da Educa\u00e7\u00e3o (FNDE).<\/p>\r\n<p style=\"text-align: justify\">Durante a visita, o reitor da Unicentro, professor F\u00e1bio Hernandes, destacou a import\u00e2ncia social da moradia estudantil e o impacto que o espa\u00e7o ter\u00e1 na vida dos estudantes. \u201c\u00c9 um sonho que est\u00e1 se concretizando. Muitos estudantes talvez n\u00e3o tivessem acesso ao ensino superior pela falta de condi\u00e7\u00f5es financeiras. Aqui eles v\u00e3o ter o seu espa\u00e7o, a sua casa enquanto estiverem na universidade. Isso \u00e9 uma vit\u00f3ria coletiva para eles e para toda a comunidade\u201d, afirmou.<\/p>\r\n<p style=\"text-align: justify\">O reitor tamb\u00e9m ressaltou que a iniciativa refor\u00e7a o papel transformador da educa\u00e7\u00e3o p\u00fablica. \u201cN\u00f3s sabemos que \u00e9 a universidade, \u00e9 o ensino que transforma vidas. A moradia estudantil tem um papel fundamental nisso. Nosso desejo \u00e9 que essa seja a primeira de muitas outras moradias, sempre pensando em quem mais precisa desse apoio para construir um futuro melhor para si e para sua fam\u00edlia\u201d, completou.<\/p>\r\n<p style=\"text-align: justify\">O deputado federal acompanha o projeto desde o in\u00edcio e destacou a import\u00e2ncia da uni\u00e3o entre diferentes esferas para que a obra sa\u00edsse do papel. \u201cTudo aquilo que discutimos nas reuni\u00f5es e defendemos na articula\u00e7\u00e3o pol\u00edtica agora est\u00e1 se concretizando. Isso daqui \u00e9 esperan\u00e7a para muitos estudantes carentes de cidades pequenas da nossa regi\u00e3o que possuem um IDH (\u00cdndice de Desenvolvimento Humano) baixo\u201d, declarou.<\/p>\r\n<p style=\"text-align: justify\">Segundo o parlamentar, o projeto dialoga diretamente com sua trajet\u00f3ria. \u201cFoi uma ideia fenomenal do professor F\u00e1bio, que se entrela\u00e7a com a minha hist\u00f3ria de vida, que vim do movimento estudantil e sempre tive isso como pauta. Ent\u00e3o unimos a sensibilidade da gest\u00e3o da universidade com a articula\u00e7\u00e3o pol\u00edtica do nosso mandato e o apoio da Seti\u201d, explicou. \u201cHoje estamos assumindo o compromisso de mobiliar toda essa casa estudantil. Espero que todos que passem por aqui tenham aprendizado, conviv\u00eancia e consigam concluir seus estudos com dignidade\u201d, disse.<\/p>\r\n<p style=\"text-align: justify\">Respons\u00e1vel pelo acompanhamento t\u00e9cnico da obra, o coordenador de Engenharia e Arquitetura da Pr\u00f3-Reitoria de Planejamento da Unicentro, Luis Carlos Ratuchne, explicou que a constru\u00e7\u00e3o j\u00e1 est\u00e1 cerca de 55% conclu\u00edda. \u201cA previs\u00e3o \u00e9 de aproximadamente mais quatro meses de obra. O projeto foi planejado em tr\u00eas pavimentos, pensando tanto na funcionalidade quanto na seguran\u00e7a dos estudantes\u201d, explicou. Segundo Luis, a estrutura contar\u00e1 com 14 su\u00edtes, sendo 12 convencionais e duas adaptadas para pessoas com defici\u00eancia (PCD), com capacidade para receber at\u00e9 56 estudantes. \u201cO pavimento inferior foi pensado para os espa\u00e7os coletivos, como lavanderia, cozinha, copa compartilhada e \u00e1rea de estudos. J\u00e1 os pavimentos superiores ser\u00e3o divididos entre masculino e feminino\u201d, detalhou.<\/p>\r\n<p style=\"text-align: justify\">O engenheiro tamb\u00e9m destacou que a localiza\u00e7\u00e3o da constru\u00e7\u00e3o foi estrategicamente escolhida dentro do c\u00e2mpus. \u201cO local foi pensado para ficar em uma regi\u00e3o central, com boa visibilidade e seguran\u00e7a, al\u00e9m da disponibilidade adequada de espa\u00e7o para esse tipo de estrutura\u201d, concluiu.<\/p>\r\n[gallery size=\"medium\" ids=\"51792,51791,51790\"]\r\n\r\n&nbsp;\r\n\r\n<em>Por Poliana Kovalyk<\/em>\r\n\r\n<hr \/>\r\n\r\n<span style=\"color: #808000\"><strong>Voc\u00ea j\u00e1 conhece o canal de transmiss\u00e3o da Unicentro no WhatsApp?<\/strong><\/span>\r\n\r\nL\u00e1, voc\u00ea encontra not\u00edcias fresquinhas e em primeira m\u00e3o, al\u00e9m de comunicados oficiais, eventos, conquistas da galera e muito mais!\u00a0<span style=\"color: #808000\"><strong><a style=\"color: #808000\" href=\"https:\/\/whatsapp.com\/channel\/0029VaBQlmUEVccJs6JPNB0N\">Clique aqui<\/a><\/strong>\u00a0<\/span>para participar e fique por dentro de tudo o que \u00e9 destaque na nossa universidade.","post_title":"Unicentro recebe visita do deputado federal Aliel Machado \u00e0s obras da Casa do Estudante","post_excerpt":"Com investimento de R$ 2,5 milh\u00f5es, moradia estudantil est\u00e1 com mais da metade das obras conclu\u00eddas.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"unicentro-recebe-visita-do-deputado-federal-aliel-machado-as-obras-da-casa-do-estudante","to_ping":"","pinged":"","post_modified":"2026-05-09 13:03:22","post_modified_gmt":"2026-05-09 16:03:22","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www3.unicentro.br\/noticias\/?p=51788","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw","mobiconnector_feature_image":{"id":51793,"alt_text":"","caption":"","description":"","media_type":"image","post":51788,"source_url":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/IMG_6380.jpg","mobiconnector_small":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_medium":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_x_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/"}},{"ID":51777,"post_author":"9","post_date":"2026-05-08T17:08:46","post_date_gmt":"2026-05-08T20:08:46","post_content":"<section class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-(--header-height)\" dir=\"auto\" data-turn-id=\"310e29d3-45cb-429a-8171-02e8d6de9e6a\" data-turn-id-container=\"310e29d3-45cb-429a-8171-02e8d6de9e6a\" data-testid=\"conversation-turn-3\" data-scroll-anchor=\"false\" data-turn=\"user\"><\/section><section class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:c87d9e8b-7095-49b3-a71d-d3debf0ff8a6-1\" data-turn-id-container=\"request-WEB:c87d9e8b-7095-49b3-a71d-d3debf0ff8a6-1\" data-testid=\"conversation-turn-4\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\r\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\r\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\r\n<div class=\"flex max-w-full flex-col gap-4 grow\">\r\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"51724930-adbb-46a0-a7c6-a0737734b561\" data-message-model-slug=\"gpt-5-5\" data-turn-start-message=\"true\">\r\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\r\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\">\r\n\r\n&nbsp;\r\n<h3 style=\"text-align: center\" data-start=\"1775\" data-end=\"1789\"><sup><em>Mais de 2,9 mil participantes de 27 institui\u00e7\u00f5es de ensino superior disputam a competi\u00e7\u00e3o em Guarapuava<\/em><\/sup><\/h3>\r\n\r\n<hr \/>\r\n<p style=\"text-align: justify\" data-start=\"855\" data-end=\"1049\">Entre os dias 7 e 10 de maio, a cidade de Guarapuava sedia a edi\u00e7\u00e3o 2026 dos Jogos Universit\u00e1rios do Paran\u00e1 (Jups). Promovida pela Secretaria de Estado do Esporte do Paran\u00e1, a competi\u00e7\u00e3o re\u00fane mais de 2,9 mil participantes de 27 institui\u00e7\u00f5es de ensino superior de diferentes regi\u00f5es do Estado.<\/p>\r\n\r\n<\/div>\r\n<p style=\"text-align: justify\">Ao todo, os Jogos contam com 361 equipes distribu\u00eddas em diversas modalidades esportivas e acad\u00eamicas. Nesta primeira etapa, ser\u00e3o realizadas disputas de atletismo, basquete, futsal, handebol, voleibol, karat\u00ea, taekwondo, basquete 3x3, jud\u00f4, xadrez, badminton, t\u00eanis e t\u00eanis de mesa, al\u00e9m da modalidade acad\u00eamica, voltada \u00e0 apresenta\u00e7\u00e3o de artigos cient\u00edficos.<\/p>\r\n<p style=\"text-align: justify\">A Universidade Estadual do Centro-Oeste (Unicentro), al\u00e9m de sediar parte das competi\u00e7\u00f5es no Complexo Desportivo e Recreativo (CDR), participa do evento com uma delega\u00e7\u00e3o formada por 65 atletas. A universidade est\u00e1 representada nas modalidades de futsal masculino e feminino, voleibol masculino e feminino, basquetebol masculino, taekwondo feminino, xadrez masculino e atletismo masculino.<\/p>\r\n\r\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\">\r\n<p style=\"text-align: justify\" data-start=\"1246\" data-end=\"1499\">Para o assessor do CDR e treinador das equipes de futsal, voleibol e atletismo da Unicentro, Odilon Penteado, a pr\u00e1tica esportiva desempenha um papel importante dentro do ambiente universit\u00e1rio. \u201cComo a atividade acontece dentro da universidade, ela se torna uma experi\u00eancia muito importante para a produ\u00e7\u00e3o cient\u00edfica dos acad\u00eamicos. Estudantes de Educa\u00e7\u00e3o F\u00edsica, Sa\u00fade, Nutri\u00e7\u00e3o, Medicina entre outros cursos podem utilizar os jogos como base para pesquisas, trabalhos acad\u00eamicos e at\u00e9 TCCs\u201d, destacou.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"1815\" data-end=\"2019\">O acad\u00eamico do primeiro ano de Educa\u00e7\u00e3o F\u00edsica da Unicentro e atleta de voleibol, Lucas Andrei Gon\u00e7alves, traz consigo a paix\u00e3o pelo esporte e destaca que representar a universidade nos Jogos Universit\u00e1rios tem um significado especial em sua trajet\u00f3ria. \u201cO v\u00f4lei sempre foi algo que eu quis seguir na minha trajet\u00f3ria. Ter a oportunidade de disputar os Jogos Universit\u00e1rios pela faculdade, agora cursando Educa\u00e7\u00e3o F\u00edsica e me preparando para atuar profissionalmente na \u00e1rea, tem um significado muito grande para mim. O esporte \u00e9 uma parte importante da minha vida e uma das coisas que mais me faz feliz\u201d, celebrou.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"2383\" data-end=\"2590\">J\u00e1 para a atleta de voleibol e acad\u00eamica do terceiro ano de Farm\u00e1cia da Unicentro, Mariana Gon\u00e7alves, a competi\u00e7\u00e3o come\u00e7ou de um jeito especial. Ap\u00f3s um ano de treinos intensos, a equipe feminina iniciou a competi\u00e7\u00e3o com vit\u00f3ria. \u201cEssa primeira vit\u00f3ria \u00e9 resultado de muita resili\u00eancia e foco do nosso time. Ano passado perdemos todos os jogos, mas neste ano nos comprometemos a melhorar, treinamos e chamamos mais meninas para formar um time mais forte\u201d.<\/p>\r\n<p style=\"text-align: justify\" data-start=\"2829\" data-end=\"2956\">Segundo Mariana, al\u00e9m da competi\u00e7\u00e3o, o esporte significa um al\u00edvio para a rotina e um espa\u00e7o de integra\u00e7\u00e3o. \u201cA gente consegue construir muitas amizades e isso \u00e9 muito importante, tanto para o desenvolvimento pessoal, quanto para ter um hobby e um momento de conviv\u00eancia. A vida universit\u00e1ria \u00e9 bastante intensa e a rotina acaba sendo muito corrida, ent\u00e3o ter um espa\u00e7o para aliviar o estresse faz muita diferen\u00e7a. Nesse sentido, eu vejo o esporte como algo fundamental na rotina\u201d, completou.<\/p>\r\n<p data-start=\"2829\" data-end=\"2956\">As disputas dos Jogos Universit\u00e1rios do Paran\u00e1 seguem at\u00e9 o dia 10 de maio nesta primeira etapa, com competi\u00e7\u00f5es realizadas em diferentes espa\u00e7os esportivos de Guarapuava. A segunda etapa dos Jups est\u00e1 programada para ocorrer entre os dias 15 e 17 de maio, tamb\u00e9m no munic\u00edpio, dando continuidade \u00e0s disputas entre as institui\u00e7\u00f5es de ensino superior participantes.<\/p>\r\n[gallery columns=\"2\" size=\"medium\" ids=\"51780,51781,51779,51778\"]\r\n<p data-start=\"2829\" data-end=\"2956\"><\/p>\r\n\r\n<\/div>\r\n<p data-start=\"2829\" data-end=\"2956\"><\/p>\r\n<p data-start=\"2829\" data-end=\"2956\"><em>Por Mylena Camargo, com supervis\u00e3o de Giovani Ciquelero<\/em><\/p>\r\n\r\n\r\n<hr \/>\r\n\r\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\">\r\n\r\n<span style=\"color: #808000\"><strong>Voc\u00ea j\u00e1 conhece o canal de transmiss\u00e3o da Unicentro no WhatsApp?<\/strong><\/span>\r\n\r\nL\u00e1, voc\u00ea encontra not\u00edcias fresquinhas e em primeira m\u00e3o, al\u00e9m de comunicados oficiais, eventos, conquistas da galera e muito mais!\u00a0<span style=\"color: #808000\"><strong><a style=\"color: #808000\" href=\"https:\/\/whatsapp.com\/channel\/0029VaBQlmUEVccJs6JPNB0N\">Clique aqui<\/a><\/strong>\u00a0<\/span>para participar e fique por dentro de tudo o que \u00e9 destaque na nossa universidade.\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/section>","post_title":"Delega\u00e7\u00e3o da Unicentro participa dos Jogos Universit\u00e1rios do Paran\u00e1","post_excerpt":"Mais de 2,9 mil participantes de 27 institui\u00e7\u00f5es de ensino superior disputam a competi\u00e7\u00e3o em Guarapuava.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"delegacao-da-unicentro-participa-dos-jogos-universitarios-do-parana","to_ping":"","pinged":"","post_modified":"2026-05-08 17:08:46","post_modified_gmt":"2026-05-08 20:08:46","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www3.unicentro.br\/noticias\/?p=51777","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw","mobiconnector_feature_image":{"id":51786,"alt_text":"","caption":"","description":"","media_type":"image","post":51777,"source_url":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-08-at-15.50.05-2.jpeg","mobiconnector_small":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_medium":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_x_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/"}},{"ID":51753,"post_author":"9","post_date":"2026-05-08T11:47:27","post_date_gmt":"2026-05-08T14:47:27","post_content":"&nbsp;\r\n<h3 style=\"text-align: center\" data-start=\"1775\" data-end=\"1789\"><sup><em>Com o tema \u201cIntelig\u00eancia Artificial na Nova Era Organizacional\u201d, evento contou com a apresenta\u00e7\u00e3o de sete trabalhos de pesquisadores da Unicentro<\/em><\/sup><\/h3>\r\n\r\n<hr \/>\r\n<p style=\"text-align: justify\">Os professores Silvio Roberto St\u00e9fani e Claudio Luiz Chiusoli, do Departamento de Administra\u00e7\u00e3o da Universidade Estadual do Centro-Oeste (Unicentro), participam nesta semana, entre os dias 7 e 9 de maio, do 10\u00b0 F\u00f3rum Internacional de Gest\u00e3o, em Faro (Portugal). Voltado a discuss\u00f5es de pesquisas e a\u00e7\u00f5es internacionais de gest\u00e3o e turismo, o congresso foi sediado pela Escola Superior de Gest\u00e3o, Hotelaria e Turismo, integrada \u00e0 Universidade do Algarve.<\/p>\r\n<p style=\"text-align: justify\">Representando a Unicentro, tamb\u00e9m participam tr\u00eas estudantes de mestrado e doutorado do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Desenvolvimento Comunit\u00e1rio (PPGDC), que apresentam projetos desenvolvidos na Universidade e realizam uma visita oficial ao Instituto Polit\u00e9cnico de Set\u00fabal.<\/p>\r\n<p style=\"text-align: justify\">Durante o evento, foram apresentados sete trabalhos de pesquisadores da Unicentro, abordando temas ligados aos Objetivos de Desenvolvimento Sustent\u00e1vel (ODSs) na Am\u00e9rica Latina, gest\u00e3o das \u00e1guas, res\u00edduos de servi\u00e7os da sa\u00fade em comunidades hospitalares, al\u00e9m de qualidade de vida no trabalho e bem-estar no servi\u00e7o policial.<\/p>\r\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Segundo o professor Cl\u00e1udio Chiusoli, \u00e9 uma oportunidade de gerar interc\u00e2mbio com profissionais do Brasil e do mundo. \u201cH\u00e1 troca de experi\u00eancia, network, ent\u00e3o \u00e9 um evento que agrega bastante da parte acad\u00eamica, cient\u00edfica e relacionamento entre academias\u201d, destaca.<\/span><\/p>\r\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Para o professor Silvio St\u00e9fani, a participa\u00e7\u00e3o no congresso proporciona o fomento de novos conhecimentos e aproxima a Unicentro de pesquisas internacionais. \u201cAgrega insights para novas investiga\u00e7\u00f5es em nossa regi\u00e3o, parcerias com universidades europeias e planos de novas a\u00e7\u00f5es para os pr\u00f3ximos anos\u201d, ressalta.<\/span><\/p>\r\n[gallery size=\"medium\" ids=\"51757,51754,51773\"]\r\n\r\n&nbsp;\r\n\r\n<em>Por Milena Kammer, com supervis\u00e3o de Giovani Ciquelero<\/em>\r\n\r\n<em>Fotos: arquivo pessoal<\/em>\r\n\r\n<hr \/>\r\n\r\n<span style=\"color: #808000\"><strong>Voc\u00ea j\u00e1 conhece o canal de transmiss\u00e3o da Unicentro no WhatsApp?<\/strong><\/span>\r\n\r\nL\u00e1, voc\u00ea encontra not\u00edcias fresquinhas e em primeira m\u00e3o, al\u00e9m de comunicados oficiais, eventos, conquistas da galera e muito mais!\u00a0<span style=\"color: #808000\"><strong><a style=\"color: #808000\" href=\"https:\/\/whatsapp.com\/channel\/0029VaBQlmUEVccJs6JPNB0N\">Clique aqui<\/a><\/strong>\u00a0<\/span>para participar e fique por dentro de tudo o que \u00e9 destaque na nossa universidade.","post_title":"Professores da Unicentro participam do 10\u00ba F\u00f3rum Internacional de Gest\u00e3o em Portugal","post_excerpt":"Com o tema \u201cIntelig\u00eancia Artificial na Nova Era Organizacional\u201d, evento contou com a apresenta\u00e7\u00e3o de sete trabalhos de pesquisadores da Unicentro.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"professores-da-unicentro-participam-do-10o-forum-internacional-de-gestao-em-portugal","to_ping":"","pinged":"","post_modified":"2026-05-08 13:44:17","post_modified_gmt":"2026-05-08 16:44:17","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www3.unicentro.br\/noticias\/?p=51753","menu_order":0,"post_type":"post","post_mime_type":"","comment_count":"0","filter":"raw","mobiconnector_feature_image":{"id":51772,"alt_text":"","caption":"","description":"","media_type":"image","post":51753,"source_url":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/2026\/05\/WhatsApp-Image-2026-05-07-at-14.05.59.jpeg","mobiconnector_small":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_medium":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/","mobiconnector_x_large":"https:\/\/www3.unicentro.br\/noticias\/wp-content\/uploads\/sites\/3\/"}}],"mobiconnector_full_category":[{"term_id":764,"name":"@ Contato","slug":"contato","term_group":0,"term_taxonomy_id":764,"taxonomy":"category","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":756,"name":"Acontece","slug":"acontece","term_group":0,"term_taxonomy_id":756,"taxonomy":"category","description":"","parent":0,"count":392,"filter":"raw"},{"term_id":787,"name":"Aviso de pauta","slug":"aviso-de-pauta","term_group":0,"term_taxonomy_id":787,"taxonomy":"category","description":"","parent":0,"count":47,"filter":"raw"},{"term_id":28,"name":"Boletins Unicentro FM","slug":"boletins-unicentro-fm","term_group":0,"term_taxonomy_id":28,"taxonomy":"category","description":"","parent":0,"count":19,"filter":"raw"},{"term_id":754,"name":"Concursos","slug":"concursos","term_group":0,"term_taxonomy_id":754,"taxonomy":"category","description":"","parent":0,"count":13,"filter":"raw"},{"term_id":753,"name":"Cultura","slug":"cultura","term_group":0,"term_taxonomy_id":753,"taxonomy":"category","description":"","parent":0,"count":281,"filter":"raw"},{"term_id":898,"name":"Destaques","slug":"destaques","term_group":0,"term_taxonomy_id":898,"taxonomy":"category","description":"","parent":0,"count":14,"filter":"raw"},{"term_id":759,"name":"Estude na Unicentro","slug":"estude-na-unicentro","term_group":0,"term_taxonomy_id":759,"taxonomy":"category","description":"","parent":0,"count":496,"filter":"raw"},{"term_id":760,"name":"Eventos","slug":"eventos","term_group":0,"term_taxonomy_id":760,"taxonomy":"category","description":"","parent":0,"count":932,"filter":"raw"},{"term_id":888,"name":"Extens\u00e3o","slug":"extensao","term_group":0,"term_taxonomy_id":888,"taxonomy":"category","description":"","parent":0,"count":36,"filter":"raw"}],"mobiconnector_next_id":null,"mobiconnector_previous_id":51848,"mobiconnector_categories":[{"cat_ID":2,"cat_name":"Not\u00edcias","cat_slug":"noticias","cat_count":6386,"cat_description":"","cat_parent":0}],"_links":{"self":[{"href":"https:\/\/www3.unicentro.br\/noticias\/wp-json\/wp\/v2\/posts\/41335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www3.unicentro.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www3.unicentro.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www3.unicentro.br\/noticias\/wp-json\/wp\/v2\/users\/274"}],"replies":[{"embeddable":true,"href":"https:\/\/www3.unicentro.br\/noticias\/wp-json\/wp\/v2\/comments?post=41335"}],"version-history":[{"count":2,"href":"https:\/\/www3.unicentro.br\/noticias\/wp-json\/wp\/v2\/posts\/41335\/revisions"}],"predecessor-version":[{"id":41396,"href":"https:\/\/www3.unicentro.br\/noticias\/wp-json\/wp\/v2\/posts\/41335\/revisions\/41396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www3.unicentro.br\/noticias\/wp-json\/wp\/v2\/media\/41341"}],"wp:attachment":[{"href":"https:\/\/www3.unicentro.br\/noticias\/wp-json\/wp\/v2\/media?parent=41335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www3.unicentro.br\/noticias\/wp-json\/wp\/v2\/categories?post=41335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www3.unicentro.br\/noticias\/wp-json\/wp\/v2\/tags?post=41335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}